{"id":2747,"date":"2019-05-13T03:47:24","date_gmt":"2019-05-13T03:47:24","guid":{"rendered":"http:\/\/unadeca.net\/cwhite4\/?page_id=2747"},"modified":"2023-03-02T17:07:07","modified_gmt":"2023-03-02T17:07:07","slug":"belice","status":"publish","type":"page","link":"https:\/\/unadeca.net\/cwhite\/belice\/","title":{"rendered":"Belice"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2747\" class=\"elementor elementor-2747\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f7425ef elementor-section-full_width section-title background elementor-section-height-default elementor-section-height-default\" data-id=\"3f7425ef\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7560df27\" data-id=\"7560df27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ef79e02 text-white elementor-widget elementor-widget-heading\" data-id=\"2ef79e02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Historia de la iglesia: Belice<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-721a2dfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"721a2dfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-781791ab\" data-id=\"781791ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-220000cb elementor-widget elementor-widget-text-editor\" data-id=\"220000cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-weight: 500;\"><strong>INICIO DE LA OBRA ADVENTISTA EN BELICE<\/strong><\/h2><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><b><strong><em>\u00a0\u00a0\u00a0\u00a0<\/em><\/strong><\/b><b><strong>Por: <\/strong><\/b><b><strong><em>Ernesto Adler Clarke, <\/em><\/strong><\/b><b><strong><em>Rigel Francis Clarke<\/em><\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><h2 style=\"font-weight: 500;\">INTRODUCCI\u00d3N<\/h2><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Es importante estudiar la historia de nuestra iglesia \u00bfPor qu\u00e9?\u00a0\u00a0La historia nos ayuda a entender el presente estudiando el pasado, la importancia de la historia reside en el hecho de que un pueblo que nos recuerda su historia, corre el riesgo de repetirla. Las cosas hoy en d\u00eda son como son gracias a la historia pasada. Nunca est\u00e1 de m\u00e1s conocer el pasado de un pueblo o el pasado de nuestra raza humana.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0La iglesia adventista del s\u00e9ptimo d\u00eda tiene su historia en Belice. Cuando Dios nos dijo el mensaje de ir por todo el mundo para predicar el evangelio hab\u00eda hombre y mujeres quienes llevaron el mensaje por todo el mundo. Vamos a estudiar la historia de la iglesia, \u00bfC\u00f3mo llego el mensaje adventista? \u00bfQui\u00e9nes fueron los personajes importantes? \u00bfQui\u00e9nes fueron los l\u00edderes\u00a0\u00a0de la iglesia adventista del s\u00e9ptimo d\u00eda? \u00bfC\u00f3mo la obra expandi\u00f3 por todo Belice? Y por \u00faltimo vamos a estudiar un poco de\u00a0\u00a0los inicios de las iglesias principales de Belice.<\/p><h1 style=\"font-weight: 500;\">DESCRIPCION DEL PAIS<\/h1><h2 style=\"font-weight: 500;\">Datos Generales de El Salvador<\/h2><p style=\"font-weight: 400;\"><a name=\"_Toc394403528\"><\/a><b><strong>Poblaci\u00f3n:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Belice cerr\u00f3 2013 con una poblaci\u00f3n de 331.900 personas, lo que supone un descenso de 11.100 personas, 3.978 mujeres y 3.862 hombres, respecto a 2012, en el que la poblaci\u00f3n fue de 343.000 personas. La poblaci\u00f3n femenina es mayoritaria, con 166.098 mujeres, lo que supone el 50.04% del total, frente a los 165.802 hombres que son el 49.95%.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403529\"><\/a><b><strong>Geograf\u00eda:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Belice est\u00e1 situado en la costa caribe\u00f1a del norte de Centroam\u00e9rica. Comparte una frontera al norte con el estado mexicano de Quintana Roo, al oeste con el departamento guatemalteco de Pet\u00e9n, y al sur con el departamento guatemalteco de Izabal. Al este del mar Caribe se encuentra la segunda barrera de arrecifes m\u00e1s larga del mundo. El \u00e1rea total del pa\u00eds es 22.960 km\u00b2, una superficie ligeramente m\u00e1s grande que El Salvador o Israel. La abundancia de lagunas a lo largo de las costas y en el interior del norte reduce el \u00e1rea real de tierra firme a 21.400 km\u00b2.\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403530\"><\/a><b><strong>Religi\u00f3n:<\/strong><\/b><b><strong>\u00a0<\/strong><\/b><\/p><p style=\"font-weight: 400;\">La libertad religiosa est\u00e1 garantizada en Belice. De acuerdo con el censo de 2010,39 40 el 40% de los belice\u00f1os son cat\u00f3licos, el 31,7% son protestantes (Pentecostal: 8,5%; Adventista: 5,5%; Anglicanismo: 4,6%; Menonita: 3,8% ; Bautista: 3,6%, Metodismo: 2,9% y Nazareno: 2,8%), el 1,7% son testigos de Jehov\u00e1, el 10,2% se adhieren a otras religiones (religi\u00f3n maya, gar\u00edfuna, Obeah y myalismo, y las minor\u00edas de mormones,hind\u00faes, budistas, musulmanes, bah\u00e1&#8217;\u00eds, rastafaris y otros) y el 15,6% no comulga con alguna religi\u00f3n.<\/p><p style=\"font-weight: 400;\"><b><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<a name=\"_Toc394403531\"><\/a>Moneda:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Belice utiliza el D\u00f3lar de Belice (BZ $ \/ BZD) la moneda, a veces err\u00f3neamente como d\u00f3lares de Belice. D\u00f3lares de EE.UU. son aceptados pr\u00e1cticamente en cualquier lugar en Belice como una forma de pago, para que los visitantes no tengan que preocuparse por cambiar d\u00f3lares de EE.UU. en D\u00f3lares de Belice. Emitido por el Banco Central de Belize (Central Bank of Belize), circulan monedas de 1, 5, 10, 25, 50 cents y de 1 d\u00f3lar, y billetes de 2, 5, 10, 20, 50 y 100 d\u00f3lares.\u00a0\u00a0Tasas de cambio es 1 EUR = 2,55 BZD (15 de noviembre de 2012), 1 USD = 2 BZD (tasa de cambio fija).<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403532\"><\/a><b><strong>Econom\u00eda:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Exportaciones: dom\u00e9sticas, az\u00facar, productos de jardiner\u00eda, jugos concentrados de naranja y toronja, productos del mar, pl\u00e1tanos y reexportaciones.<\/p><p style=\"font-weight: 400;\">Importaciones: A principios de la d\u00e9cada de los ochenta, las exportaciones anuales ascend\u00edan a 28.6 millones de d\u00f3lares y el costo de las importaciones a 545.3 millones.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403533\"><\/a><b><strong>Culturas:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En Belice se distinguen varios tipos de razas:<\/p><ul style=\"font-weight: 400;\"><li>Los Creoles, que son descendientes de los esclavos Africanos y los Brit\u00e1nicos colonos. Los Creoles en Belice han modelado su cultura a la brit\u00e1nica. La mayor\u00eda hablan ingl\u00e9s, aunque para hablar en casa y en situaciones informales usan un ingl\u00e9s creole Belice\u00f1o.<\/li><li>Mestizos, son una mezcla de sangre India y Europea. Los mestizos de habla hispana llegaron a Belice a mediados del siglo XIX y en los \u00faltimos 20 a\u00f1os han crecido tremendamente en n\u00famero.<\/li><li>Indios Mayas. Los Mayas llegaron a Belice en el a\u00f1o 100 despu\u00e9s de Cristo. Los Mayas modernos son principalmente inmigrantes de Guatemala y M\u00e9jico. Hay tres grupos diferentes de Mayas en la moderna Belice, cada uno tiene su propio idioma y sus propias tradiciones y cultura.<\/li><li>Garifuna, tambi\u00e9n llamados Caribe\u00f1os Negros, son una cultura \u00fanica descendiente de los Indios Caribe\u00f1os y los Africanos en el este Caribe\u00f1o en el siglo XVIII. Su idioma se basa en el Caribe\u00f1o, aunque la mayor\u00eda pueden hablar ingl\u00e9s o espa\u00f1ol.<\/li><li>Indios del Este llegaron a Belice en los a\u00f1os 1840, siendo contratados para trabajar en las colonias Brit\u00e1nicas del Caribe.<\/li><li>Mennonites llegaron a Belice despu\u00e9s de 1958, cuando se les otorg\u00f3 exenci\u00f3n del servicio militar y seguro obligatorio. Llegaron de M\u00e9jico y Canad\u00e1, recibiendo permiso del gobierno para establecer tres colonias en Blue Creek, Shipyard y Spanish Lookout.<\/li><\/ul><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403535\"><\/a><b><strong>Idiomas:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El idioma oficial de Belice es el ingl\u00e9s, pero los criollos (el grupo \u00e9tnico m\u00e1s nutrido) hablan junto a \u00e9ste su propio dialecto. El espa\u00f1ol es la lengua m\u00e1s utilizada en el Norte y en algunos pueblos occidentales. As\u00ed mismo existen minor\u00edas que se expresan en maya, chino, alem\u00e1n menonita, liban\u00e9s, \u00e1rabe, hindi y garifuna (el idioma de los garinagu del distrito de Stann Creek).<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403537\"><\/a><b><strong>Clima:<\/strong><\/b><b><strong>\u00a0<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El clima local es tropical y normalmente muy c\u00e1lido y h\u00famedo, aunque hay variaciones significativas en los patrones del clima por regi\u00f3n. Las temperaturas var\u00edan seg\u00fan la elevaci\u00f3n, proximidad a la costa, y los efectos moderadores de los vientos alisios del noreste fuera del Caribe. Las temperaturas medias en las regiones costeras oscilan desde los 24 \u00b0C en enero a los 27 \u00b0C en julio. Las temperaturas son ligeramente m\u00e1s altas hacia el interior, excepto en las mesetas altas del sur, tales como el Mountain Pine Ridge, donde el clima es notablemente m\u00e1s fr\u00edo. En general, las estaciones est\u00e1n marcadas m\u00e1s por las diferencias de humedad y precipitaci\u00f3n que por las de temperatura.<\/p><p style=\"font-weight: 400;\">Belice est\u00e1 dividido en seis distritos:<\/p><ol style=\"font-weight: 400;\"><li>Belice\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/li><li>Cayo<\/li><li>Corozal<\/li><li>Orange Walk<\/li><li>Stann Creek<\/li><li>Toledo<\/li><\/ol><h2 style=\"font-weight: 500;\">Historia:<\/h2><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Belice es el \u00fanico pa\u00eds de Centroam\u00e9rica con un patrimonio Brit\u00e1nico en vez de espa\u00f1ol, aunque comparte parte de su historia con la de sus pa\u00edses vecinos de habla hispana. Belice, como M\u00e9xico y Honduras, fue tambi\u00e9n gobernada por la cultura Maya. Los primeros Europeos que llegaron a Belice fueron los espa\u00f1oles. A finales del siglo XV, los espa\u00f1oles intentaron monopolizar el Caribe y Centroam\u00e9rica, dejando Brasil para los portugueses. Los espa\u00f1oles tambi\u00e9n trataron de establecer el Catolicismo en el siglo XVII, pero se les oblig\u00f3 a abandonar la zona. Los espa\u00f1oles, a pesar de haber reclamado Belice, no establecieron un gobierno efectivo en aquel entonces. Durante el siglo XVIII los espa\u00f1oles atacaron a los brit\u00e1nicos que se hab\u00edan asentado en la costa y los echaron del pa\u00eds temporalmente. Sin embargo, los espa\u00f1oles nunca se asentaron en Belice, dejando el camino libre para los brit\u00e1nicos. Los brit\u00e1nicos volvieron a Belice, convirti\u00e9ndose en le\u00f1adores. Belice se proclam\u00f3 una colonia de Honduras Brit\u00e1nica en 1862. Los Brit\u00e1nicos no pudieron usar a los Mayas para obligarlos a trabajar cortando \u00e1rboles, por lo que trajeron esclavos de \u00c1frica a principios del siglo XVIII. La esclavitud fue abolida en 1838. El 21 de septiembre de 1981, Belice declar\u00f3 su independencia.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403527\"><\/a><b><strong>Independencia:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Las reformas constitucionales se iniciaron en 1954 y dieron lugar a una nueva Constituci\u00f3n diez a\u00f1os m\u00e1s tarde. Gran Breta\u00f1a concedi\u00f3 a la Honduras Brit\u00e1nica el autogobierno en 1964, y el l\u00edder del PUP, George Price, se convirti\u00f3 en primer ministro de la colonia. La Honduras Brit\u00e1nica fue rebautizada oficialmente como \u00abBelice\u00bb en 1973. El progreso hacia la independencia, sin embargo, se vio obstaculizado por un reclamo guatemalteco de la soberan\u00eda del territorio. Belice, finalmente, alcanz\u00f3 la plena independencia el 21 de septiembre de 1981, aunque Guatemala se neg\u00f3 a reconocer a la nueva naci\u00f3n. Unos 1.500 soldados brit\u00e1nicos se quedaron para proteger Belice de la amenaza guatemalteca.<\/p><p style=\"font-weight: 400;\">Con Price a la cabeza, el PUP gan\u00f3 todas las elecciones hasta 1984. Ese a\u00f1o el PUP fue derrotado por el Partido Democr\u00e1tico Unido (UDP), y el l\u00edder de la UDP, Manuel Esquivel, reemplaz\u00f3 a Price como Primer ministro belice\u00f1o. Price regres\u00f3 al poder tras las elecciones de 1989. El presidente de Guatemala reconoci\u00f3 formalmente la independencia de Belice en 1992. Al a\u00f1o siguiente, el Reino Unido anunci\u00f3 que pondr\u00eda fin a su participaci\u00f3n militar en Belice. Los soldados brit\u00e1nicos se retiraron en 1994, pero el Reino Unido dej\u00f3 una unidad de entrenamiento militar para ayudar en la reci\u00e9n creada Fuerza de Defensa de Belice.<a href=\"http:\/\/cwhite.unadeca.net\/index.php\/es\/article-category\/investigaciones\/historia-de-la-iglesia\/belice#_ftn1\" name=\"_ftnref1\"><\/a><\/p><h2 style=\"font-weight: 500;\">LA OBRA ADVENTISTA EN BELICE<\/h2><h3 style=\"font-weight: 500;\">ESFUERZO MISIONERO<\/h3><h4 style=\"font-weight: 500;\">Los Inicios de la obra adventista en El Belice.<\/h4><p style=\"font-weight: 400;\"><a name=\"_Toc394403540\"><\/a><b><strong>DISTRITO DE COROZAL<\/strong><\/b><\/p><p style=\"font-weight: 400;\">La obra de la iglesia adventista en el Distrito de Corozal comenz\u00f3 en Pembroke Hall en la urbanizaci\u00f3n de Estrella\u00a0\u00a0en el a\u00f1o 1931 por un colportor llamado Rodwell Gibson. Despu\u00e9s de Rodwell Gibson un hombre llamado por Dios Felipe Clarke fue el l\u00edder de los creyentes en esa \u00e9poca de los inicios del movimiento. Felipe Clarke fue a Pembroke hall para construir la iglesia para los primeros 32 creyentes. Felipe Clarke era el hombre de Dios escogido para llevar el mensaje de\u00a0\u00a0esperanza a muchos.<\/p><p style=\"font-weight: 400;\">En el a\u00f1o 1934 la iglesia del pueblo de Corozal fue fundado primero en la finca del Sr. Alfred Anderson por la Sra. Christiline Gill. C.B Sulton llevo la iglesia a una nueva ubicaci\u00f3n en la cual fue en el centro del pueblo de Corozal, adonde ahora est\u00e1 la iglesia central de Corozal.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403541\"><\/a><b><strong>Los pillares de la Iglesia Adventista en el pueblo de Corozal:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El hermano Sabido despu\u00e9s de trabajar en la Misi\u00f3n adventista de Belice fue enviado a trabajar en Corozal como Instructor B\u00edblico. Trabajo juntamente con el pastor\u00a0\u00a0Fulton Archbold, juntos bautizaron 21 personas para el reino de Dios. El pastor Fulton Archbold poco despu\u00e9s fue el presidente de la Misi\u00f3n de la Honduras Brit\u00e1nica.\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"100%\"><tbody><tr><td><p>El Centro de Corozal en 1930\u00a0<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\">El hermano Andrew Gilharra fue un laico para la iglesia adventista del s\u00e9ptimo d\u00eda. El estableci\u00f3 puntos de predicaci\u00f3n en muchas aldeas. Dos veces fue el laico del a\u00f1o por haber ganado m\u00e1s almas para el Se\u00f1or. Fue enviado a Jamancia para los seminarios de laicos. El hacia 3-4 campa\u00f1as al a\u00f1o aun estando a los 80 a\u00f1os de edad. Su \u00faltima cursada fue en Chan Chen y su \u00faltimo serm\u00f3n fue en la iglesia central de Corozal.<\/p><p style=\"font-weight: 400;\">El hermano Alfred Alcala puso su servicio para la iglesia de central de corozal. Por m\u00e1s de 30 a\u00f1os fue anciano, tesorero y maestro de la escuela sab\u00e1tica. \u00c9l le daban importancia a los necesitados en supli\u00e9ndoles con comida y estudio de nivel secundario. Antes de su muerte el dio donativos para la construcci\u00f3n de la iglesia central de Corozal.<\/p><p style=\"font-weight: 400;\">Edna Williams era la pianista de la iglesia central de corozal. Siempre estaba puntal y hacia sus deberes que ten\u00edan con la iglesia de manera alegre.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Los esposos Whittaker eran como Aquila y prisilla en los tiempos de pablo. Ellos se entregaron en la obra misionera para que obra se expandiera m\u00e1s en el distrito de corozal.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403542\"><\/a><b><strong>La iglesia en Santa Clara:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El hermano Sabido en los a\u00f1os 1950 fue a santa clara para llevar el mensaje adventista. Ah\u00ed dio estudios b\u00edblicos a muchos pero los m\u00e1s sobresalientes fueron Bruno Canul y Julio Casta\u00f1eda. Por lo tanto la iglesia se compuso de la familia Canul, Casta\u00f1eda y los Cans. En 1955 se hizo una gran campa\u00f1a con el evangelista R.T Rankin y su traductor pastor Wilbert Oliver y se\u00a0\u00a0expandi\u00f3 la iglesia en Santa Clara con un total de 40 miembros.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403543\"><\/a><b><strong>La iglesia en Patchakan:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El hermano Higinio Maga\u00f1a y juntamente con su familia celebraban una serie de escuela sab\u00e1tica en Patchakan. Despu\u00e9s de dos a\u00f1os el hermano Maga\u00f1a predico un serm\u00f3n para el a\u00f1o\u00a0\u00a0nuevo bas\u00e1ndose en el \u201ccamino a Cristo\u201d y se bautizaron por primera vez 22 personas y el pastor Gustavo Gill los bautizo.\u00a0\u00a0Pocos despu\u00e9s del bautismo una iglesia se establecio para la gloria de nuestro Dios.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403544\"><\/a><b><strong>La iglesia de san Joaqu\u00edn:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Los miembros de la iglesia adventista que viv\u00edan en San Joaqu\u00edn ten\u00edan que caminar hasta Calcutta adonde se encontraba una iglesia adventista. A veces ten\u00edan que caminar bajo la lluvia y calor del sol para llegar hasta la iglesia. El hermano Higinio Maga\u00f1a\u00a0\u00a0te\u00edna un sue\u00f1o de que se edificara\u00a0\u00a0una iglesia en San Joaqu\u00edn. Los hermanos de Calcutta cre\u00edan que el hermano Maga\u00f1a quiera separa la iglesia. Finalmente una iglesia adventista se edific\u00f3 en San Joaqu\u00edn. El pastor Victor Sheperd era el presidente de la Misi\u00f3n de Belice en aquel tiempo, y\u00a0\u00a0fue el quien organizo la iglesia de San Joaqu\u00edn.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403545\"><\/a><b><strong>La iglesia de Chan Chen:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En el hogar de sr. \u00c1lvaro Gilharry se celebraba una serie de escuela sab\u00e1tica y como resultado se bautizaron 15 personas por el pastor Lionel Pottinger. Las personas quienes tuvieron parte en la formaci\u00f3n de la iglesia adventista del s\u00e9ptimo d\u00eda fueron el pastor Oswaldo Maga\u00f1a, y el hermano Fr\u00e1ncico Quetzal\u00a0\u00a0y familia. Con el esfuerzo de ellos se logr\u00f3 edificarse una iglesia adventista.\u00a0\u00a0El hermano Henry Gilharry dono el terreno para la construcci\u00f3n de la iglesia. El hermano Henry era conocido como \u201cfireman\u201d por su celo en la predicaci\u00f3n del evangelio en Corozal.\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403546\"><\/a><b><strong>La iglesia de Caledonia:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El hermano Higinio Maga\u00f1a iba a caledonia para vender libros con su bicicleta. En caledonia vio la necesidad de los hermanos que viv\u00edan ah\u00ed quieran\u00a0\u00a0tener una iglesia. Los hermanos adventistas del s\u00e9ptimo d\u00eda ten\u00edan que ir a Pembroke hall para adora a Dios porque no ten\u00edan una iglesia en caledonia y la distancia era demasiado lejos. El hermano Higinio oro con mucho fervor para que se estableciera una iglesia en Caledonia. El pastor Caleb Clayton bautizo tres personas en caledonia y un terreno se obtuvo para la iglesia y el hermano Felipe Clarke dono las sillas para la iglesia. Despu\u00e9s en los 1980s una iglesia nueva se construy\u00f3.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403547\"><\/a><b><strong>La iglesia de Ranchito:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"100%\"><tbody><tr><td><p>Artemio Clarke<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\">En abril de 1989 cinco hermanos de la iglesia en Calcutta decidieron realizar una campa\u00f1a evangelista en la aldea de Ranchito. La campa\u00f1a trajo frutos\u00a0\u00a0y nuevos conversos se reun\u00edan cerca de la residencia del hermano Daniel. Pero hab\u00eda una necesidad de un templo para adorar. El hermano Hemsley Jones ofreci\u00f3 un lugar para la iglesia. Los hermanos necesitaban dinero para la construcci\u00f3n. Por lo tanto la iglesia de Calcutta ofreci\u00f3 cierta cantidad y la misi\u00f3n de Belice ofreci\u00f3 $ 1,000. El l\u00edder de la iglesia Artemio Clarke siempre animo a los hermanos con estas palabras \u201cComenzamos con fe y terminaremos con fe\u201d.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403548\"><\/a><b><strong>La iglesia de San Andr\u00e9s:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"100%\"><tbody><tr><td><p>Francisco Clarke<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\"><b><strong>\u00a0<\/strong><\/b>En abril de 1995 el pastor Reynaldo Canales y con la ayuda de los hermanos de la iglesia\u00a0Xaibe hicieron una campa\u00f1a en san Andr\u00e9s y solamente dos fueron bautizados. En\u00a0\u00a0mayo 1995 los hermanos Clarke, Artemio Clarke y\u00a0\u00a0Francisco Clarke y juntamente con los hermanos de la iglesia de Xaibe hicieron otra campa\u00f1a. Cuatro m\u00e1s personas fueron bautizados. Octubre 1997 el grupo de Maranta vino a construir un templo para creyentes.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403549\"><\/a><b><strong>DISTRITO DE ORANGE WALK<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">En 1962 el pastor Ellis Coe fue enviado a trabajar en Orange Walk para la obra del evangelio.\u00a0\u00a0En 1969 el Pastor hizo una Campa\u00f1a con la ayuda del pastor Lindel Dixon y el pastor Patricio P\u00e9rez.\u00a0\u00a0Las reuniones comenzaron para dos meses y durante las noches de reuni\u00f3n satan\u00e1s trabajo arduamente con la voz del pastor Coe. Al terminar la campa\u00f1a 28 personas fueron bautizados para la gloria del Se\u00f1or.\u00a0\u00a0Los quienes lideraban la iglesia en aquel entonces era la familia Roberts y guerra, la hermana Distan y otros.\u00a0\u00a0En 1972 la iglesia de Orange Walk fue dedicado para la honora y Gloria de nuestro Dios. El sr. Manuel Guerra y su esposa aceptaron el mensaje adventista. \u00c9l fue hombre de Dios y trabajo fuertemente para la expansi\u00f3n de la obra de Dios. El siempre utilizo sus dones y talento para el servicio de Dios.\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403550\"><\/a><b><strong>La iglesia en Douglas:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Todo comenz\u00f3 con dos familias adventista del s\u00e9ptimo d\u00eda, en la cual eran las familias Carillo y Corea, ellos ten\u00edan servicio en la casa del hermano Patronilo Carillo. Pero los aldeanos no\u00a0\u00a0estaban contentos con la familia porque profesaban otra fe en vez de la cat\u00f3lica.<\/p><p style=\"font-weight: 400;\">En noviembre 1963 el pastor Coe fue enviado a Douglas para fortalecer\u00a0\u00a0a los hermanos en la fe. Mientras que predicaba una noche, los aldeanos comenzaron a tirar piedras hacia el lugar de las reuniones. Gracias a Dios ninguno fue lastimado. La obra en Douglas se realiz\u00f3 con todo el esfuerzo no importando la vida porque satan\u00e1s no estaba contento con el mensaje adventista.\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403551\"><\/a><b><strong>La iglesia en Guinea Grass:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Las familias Gomez, Cans, y los Cima sostuvieron la antorcha de verdad en Guinea Grass. Ellos se reun\u00edan en la residencia del el hermano Cima para adorar a Dios. Los hermanos buscaron ayuda a los hermanos de Calcutta y Tower Hill para expandir en mensaje. Entre los hermanos que fueron eran Artemio Clarke, Francisco Clarke, Mois\u00e9s Cab, Sr. Ek, Francisco Roberts y la familia Gillett.\u00a0\u00a0Los pastores quienes causaron grandes impactos en Guinea Grass fueron el Pr. Wilbert Oliver y el\u00a0\u00a0Pr. Ernesto Clarke.\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><b><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/b><a name=\"_Toc394403552\"><\/a><b><strong>DISTRITO DE BELICE<\/strong><\/b><\/p><p style=\"font-weight: 400;\">La obra del mensaje adventista del s\u00e9ptimo d\u00eda comenz\u00f3 en los a\u00f1os 1800s con el pastor F.J Hutchins. En 1885 la sra. E. Gauterau vino desde las islas de honduras para repartir literatura adventista. 1892 se reparti\u00f3 m\u00e1s literatura adventista por F.J. Hutchins. En los 1900s el pastor H.C. Goodrich y juntamente con su esposa consiguieron un lugar en Belice para realizar los primeros cultos de adoraci\u00f3n adventista. En 1922 el hermano Carey vend\u00eda libros y Biblias. Estos fueron los primeros esfuerzos para establecer la iglesia adventista. Atreves de estos esfuerzos 14 personas fueron bautizados. Un edificio fue levantado en Yarborough para ser la iglesia adventista del s\u00e9ptimo d\u00eda y casa misionera. 1937 ya hab\u00edan 300 adventistas del s\u00e9ptimo d\u00eda. En 1950 ya hab\u00eda m\u00e1s de 12 iglesias y m\u00e1s de 400 miembros.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403553\"><\/a><b><strong>La iglesia de Good News:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En el a\u00f1o 1988 la notica de Jes\u00fas se expandi\u00f3 en el \u00e1rea del sur de Belice. Un grupo peque\u00f1o fue formado\u00a0\u00a0de la iglesia de Zion. La hermana Sylvia Lord fue el l\u00edder del grupo. El grupo fue a\u00a0\u00a0hacer la campa\u00f1a con la ayuda del esp\u00edritu santo. El pastor Dennis y el grupo fue usado para establecer una nueva iglesia en la cuidad de Belice.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403554\"><\/a><b><strong>La iglesia de san Pedro, Ambergris caye:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En 1930 el hermano Sabido fue a San pedro como colportor e instructor b\u00edblico. Hab\u00eda muchas personas que estaba interesados en el mensaje. El hermano sabido estaba entusiasmado por la obra en San pedro que le dijo a C.B Sutton de la situaci\u00f3n de San pedro y Ronaldo Robertson fue enviado a ayudar al hermano Sabido por un mes. Como resultado 22 personas fueron bautizadas y poco despu\u00e9s otros 10 personas. La hermana Christiline Gill fue enviada para trabajar en obra y bautizo a 10 personas. Los primeros miembros eran de 42 personas.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403555\"><\/a><b><strong>El trabajo medico:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En febrero 24, 1995 la misi\u00f3n de Belice abri\u00f3 la cl\u00ednica adventista del s\u00e9ptimo d\u00eda en ladyville. La doctora Ranju Prakasam fue encargada de la clinica, ella trabajo en departamento de salud del uni\u00f3n y en el hospital adventista Loma luz en Santa Elena. Otros doctores adventistas como Dr. Trummer y el Dr. Mundall establecieron hospitales en Belice.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0La iglesia en Sibun River comenz\u00f3 con la familia Smiths en los a\u00f1os 1960s en la cuales establecieron reuniones de adoraci\u00f3n en los s\u00e1bados. Despu\u00e9s muchos fueron unidos en el grupo y el grupo aumento hasta 25 miembros.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"100%\"><tbody><tr><td><p>La clinica Adventista en ladyville<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">La iglesia de Biscayne comenz\u00f3 con cuarto familias las cuales son los rodas, Flowers, Cox, y los Dawson. En el a\u00f1o 1967 los hermanos Jerome Bevans y Norman Westby hicieron campa\u00f1as y la membres\u00eda se aument\u00f3.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403556\"><\/a><b><strong>DISTRITO DE CAYO<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Para el Pastor Coe fue una bendici\u00f3n conocer al hermano y la hermana Raisin, una pareja de ancianos en cuyos labios estaban siempre las alabanzas de Dios. Siempre se pod\u00eda escuchar &#8220;\u00a1Am\u00e9n y Am\u00e9n!&#8221; que se hac\u00eda eco a trav\u00e9s de los servicios por parte de estos guerreros de Dios. Unieron sus esfuerzos con la hermana Violet James, una mujer piadosa que \u00fanica ambici\u00f3n era llevar el mensaje de Dios en el Distrito de Cayo. En 1968, el Pastor Aquilino fue enviado para ayudarlos.<\/p><p style=\"font-weight: 400;\">Adoraron durante un tiempo bajo un \u00e1rbol de mango. Cuando el Pastor Jesse se fue, Pastor Albert Reid lleg\u00f3 a hacerse cargo de la obra. Que m\u00e1s tarde se reunieron para los servicios en las instalaciones de la Borland en un remolque perteneciente al Dr. Ray Mundall que acababa de llegar de los Estados Unidos de Am\u00e9rica para trabajar entre la gente de ese pueblo.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">En ese momento s\u00f3lo hab\u00eda ocho miembros: las hermanas Eloisa y Alindy August, Antonia Antonette y la familia de Borland. Pronto el grupo y el Pastor pudieron obtener un pedazo de tierra en Santa Elena del vecino de Borland para construir la primera Iglesia Adventista del S\u00e9ptimo D\u00eda en el Distrito de Cayo. El constructor fue el Hermano David Perrera del Distrito de Corozal.<\/p><p style=\"font-weight: 400;\">Dos colportores, el hermano Morgan y Carl Butler ayudaron a dar estudios b\u00edblicos a los interesados y estaban dispuestos a ir todo el camino con el Se\u00f1or asistiendo y tambi\u00e9n colaborando con\u00a0\u00a0la m\u00fasica para la Cruzada.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403557\"><\/a><b><strong>Radio y Televisi\u00f3n:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"10\"><tbody><tr><td>\u00a0<\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\">A finales de 1950 cuando el Pastor Elden Ford, fue el presidente de la Misi\u00f3n de Belice y el hermano Wilfred Moncrieffe como tesorero, la voz de la profec\u00eda difundi\u00f3 un Programa de salud que se llamaba \u2018Your Radio Doctor\u2019 (Su M\u00e9dico de radio) por Clifford Anderson. El programa sali\u00f3 al aire en el radio de Belice, la \u00fanica estaci\u00f3n de radio en ese momento. Los ricos y los pobres pudieron escuchar de estos programas y fueron bendecidos. Durante una d\u00e9cada, programas como estos no se escucharon hasta que \u201cFaith F.M.\u201d la estaci\u00f3n de radio fue abierto y dedicado el 2 de enero de 1999.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0El Pastor Leslie Gillett representante de la misi\u00f3n de Belice Adventista del S\u00e9ptimo D\u00eda, y V\u00edctor Gonz\u00e1lez, PH: D, Director General en el Ministerio de Servicios P\u00fablicos, Transporte y Comunicaciones dieron palabras de apertura.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"100%\"><tbody><tr><td><p>Pastor Guy Nemhard<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0El Honorable Daniel Silva, Ministro de Agricultura y Pesca, declar\u00f3 la emisora de radio abierto. La iglesia de San Ignacio por nombre de \u2018Let God speak\u2019 (Deja que Dios hable) y las Iglesias de Santa Elena colaboraron con la m\u00fasica para la esa ocasi\u00f3n. Pastor Guy Nemhard y Pastor Coe compartieron en la dedicatoria que fue seguido por un recorrido por las instalaciones. Despu\u00e9s de la ceremonia de apertura se sirvi\u00f3 un refrigerio a los que asistieron.\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">La radio es propiedad privada del hermano Windell Borland Jr. y miembros de su familia que le dan apoyo, y que est\u00e1 haciendo un trabajo excepcional.<\/p><p style=\"font-weight: 400;\">A trav\u00e9s de este ministerio, Belice y m\u00e1s all\u00e1, como M\u00e9xico y Guatemala oyen estos programas internacionales como &#8220;La voz de la Profec\u00eda, Porque est\u00e1 Escrito: La Hora Tranquila y los Tres \u00c1ngeles etc\u201d, como resultado, m\u00e1s personas est\u00e1n respondiendo al mensaje, iglesias y escuelas se han construido como resultado de este ministerio.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403558\"><\/a><b><strong>Georgeville<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><b><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/b>En abril de 1986, el mensaje tambi\u00e9n fue predicado en Georgeville, un pueblo a nueve millas de la ciudad de Santa Elena, Cayo. La familia Segura generosamente nos ofreci\u00f3 una secci\u00f3n de su casa como un lugar de encuentro para las reuniones. Durante una serie de dos meses de la reuni\u00f3n que se estaba llevando a cabo y con la ayuda de la Iglesia de Santa Elena, el Esp\u00edritu Santo toco muchos corazones al arrepentimiento que m\u00e1s tarde dieron sus vidas a Jesucristo a trav\u00e9s del bautismo.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Los ancianos Hector Cadle y Victor August ayudaron con el programa de las noches y tambi\u00e9n con las visitaciones. Al final de la serie, los nuevos miembros y los interesados fueron transportados a la iglesia de Santa Elena para los servicios de adoraci\u00f3n. Con la ayuda de Dios una Iglesia fue construido en un pedazo de tierra de la familia Segura. El hermano Hector Cadle, Profesor Raymond Mortis y sus familias se hicieron cargo del nuevo grupo para unos a\u00f1os.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403559\"><\/a><b><strong>Belmopan<\/strong><\/b>:<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Los primeros en llegar con el mensaje en la nueva capital del pa\u00eds de Belice, Belmopan, ubicado a 50 kil\u00f3metros de distancia de la ciudad, fueron dos predicadores laicos, Jerome Bevans y Norman Westby que vinieron de la antigua capital que era la ciudad de Belice.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Por un tiempo, ellos adoraban en la casa de la Sra. Evelyn Haylock y luego obtienen un edificio en la calle Kiskidee, donde continuaron reuni\u00e9ndose para los servicios semanales.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0En 1980 la misi\u00f3n invit\u00f3 al\u00a0\u00a0evangelista Dobias de los Estados Unidos de Am\u00e9rica para llevar a cabo una serie de reuniones de campa\u00f1a. Predicaba cada noche durante m\u00e1s de un mes. Con la ayuda de los predicadores laicos, Pastor Usher y Pastor Sombrerero, la verdad presente se proclam\u00f3 en Belmopan. Las reuniones concluyeron con 42 personas entregando sus corazones a Dios por medio del Bautismo.<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Los laicos continuaron manteniendo en alto el estandarte del pr\u00edncipe Emmanuel llevando adelante el trabajo. Hermano Bevans y el hermano Norman Westby celebraron reuniones en Roaring Creek, y luego otro hermano laico Ricardo Correa se uni\u00f3 a las reuniones en Salvapan y como resultado iglesias fueron establecidos en estas \u00e1reas.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403560\"><\/a><b><strong>DISTRITO DE STANN CREEK<\/strong><\/b><\/p><p style=\"font-weight: 400;\">En los a\u00f1os 30 Pastor Overstreet entr\u00f3 en el distrito de Stann Creek acompa\u00f1ado por un\u00a0joven pastor Leopold Garbutt y sus amigos.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">Se realizaron reuniones en la casa de la abuelita Garbutt. Atreves de las semanas, otros fueron atra\u00eddos y se unieron a la familia de Garbutt. El Belisles, Pantings, Parkings, Hermano Hern\u00e1ndez y algunos de los hermanos que emigraron de Jamaica se fueron agregando y aument\u00f3 el n\u00famero del grupo.<\/p><p style=\"font-weight: 400;\">Cuando el pastor estaba ausente, la abuelita Garbutt lideraba el grupo. Una caracter\u00edstica especial de esta iglesia es que las hermanas siempre llevaban a cabo los servicios. Las hermanas Gabourel, Grant, Johnson, Lydia Smith y Bonilla siempre serv\u00edan a la iglesia para glorificar el nombre de Dios.<\/p><p style=\"font-weight: 400;\">En abril de 1977, Pastor Coe fue enviado de vuelta al distrito de Stann Creek. La cual empez\u00f3 hacer preparaciones para una gran cruzada por de parte de la uni\u00f3n por el evangelista BL Roberts.<\/p><p style=\"font-weight: 400;\">Se llevaron a cabo las reuniones, durante 8 semanas. Trabajaron d\u00eda y noche estudiando con los interesados y despu\u00e9s de cuatro semanas, s\u00f3lo dos personas aceptaron la verdad. Los trabajadores comentaron acerca de lo dif\u00edcil que era el campo pero al final de la cuarta noche, 15 personas fueron bautizadas. Cuando el pastor Roberts se fue, se llev\u00f3 a cabo reuniones de seguimiento en la iglesia y se pudo bautizar a ocho m\u00e1s, con lo que la Cruzada Dangriga llego a un total de 25 preciosas almas para el reino de Dios.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">La esposa de un hombre de negocios asisti\u00f3 a reuni\u00f3n de la tarde el domingo en la iglesia. Ella hizo su decisi\u00f3n de ser bautizada, cuando el pastor de Guy Nemhard celebr\u00f3 una semana de oraci\u00f3n durante dos semanas. Cuando ella fue a su casa tuvo que enfrentarse a un esposo enojado que la amenaz\u00f3 dici\u00e9ndole que su bautismo iba poner fin a su matrimonio.<\/p><p style=\"font-weight: 400;\">Mientras se llevaba a cabo una reuni\u00f3n una noche, se me inform\u00f3 de este grave asunto de esa familia. Inmediatamente el Pastor Nemhard y Pastor Coe, fueron a visitar la casa. Al entrar, el marido todav\u00eda estaba enojado, e insisti\u00f3 en que la esposa hab\u00eda desafiado a sus \u00f3rdenes en ser bautizada, y eso ser\u00e1 el final de todo. Se dice que era dif\u00edcil calmarlo; que estaban all\u00ed por dos a tres horas tratando de razonar con \u00e9l. Lo animaron a unirse a orar por la decisi\u00f3n que su esposa hab\u00eda tomado. Tambi\u00e9n le dieron una invitaci\u00f3n para asistir a la noche siguiente de servicio. Dios hizo un milagro. Ese s\u00e1bado por la noche una sorpresa se vio cuando el marido y la mujer entran en la iglesia juntos, y se sentaron para escuchar la palabra de Dios.<\/p><p style=\"font-weight: 400;\">El nunca dej\u00f3 de asistir despu\u00e9s de esa experiencia. De hecho, su esposa dijo que despu\u00e9s de cada servicio al regresar a casa ense\u00f1aba a sus hijos la lecci\u00f3n que se hab\u00eda estudiado en la iglesia. Y para sorpresa quer\u00eda ser bautizar el d\u00eda despu\u00e9s de la navidad. Y as\u00ed lo hizo, y la pareja fue feliz hasta la muerte.\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403561\"><\/a><b><strong>Iglesia de Independence:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">La familia Burgess y Coleman fueron los primeros en salir de sus casas de la aldea de Monkey River, para buscar trabajo en Mango Creek. Mientras que estaban en esta nueva \u00e1rea ellos y otros se reunieron para los cultos en la casa del hermano Milton Burgess.\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">Un misionero laico llamado Robert Gross, siempre estaba dispuesto a trabajar para Dios. Hizo una cruzada en Mango Creek por tres semanas y tuvo buenos resultados. Doce almas estaban dispuesto entregar sus vida a Jes\u00fas. Cuando el pastor Coe fue a bautizar a los candidatos para el hermano Gross, hab\u00eda una inundaci\u00f3n; y era dif\u00edcil cruzar con el veh\u00edculo, pero el hermano Milton entro en las aguas de la inundaci\u00f3n, se acerc\u00f3 a donde estaba el pastor Coe y le dijo que se sentara sobre sus hombros. Y lo cruzo al\u00a0\u00a0otro lado y el Pastor Coe pudo hacer el bautismo.<\/p><p style=\"font-weight: 400;\">El Pastor Coe decidi\u00f3 hacer una campa\u00f1a en Dangriga y quedo con la familia Burgess para esos meses de evangelismo. La asistencia de la cruzada fue muy buena. El hermano Burgess ayudo con la m\u00fasica para la cruzada con canciones que tocaba cada coraz\u00f3n. La gente tambi\u00e9n vio el mensaje a trav\u00e9s de im\u00e1genes de movimiento. Un fuerte impacto se hizo sobre la aldea. Con la bendici\u00f3n de Dios el n\u00famero del grupo aumento.\u00a0<\/p><p style=\"font-weight: 400;\">El\u00a0\u00a0hermano Santos y su familia ten\u00edan un problema con las personas de habla hispana que viv\u00edan en la aldea de Independence. \u00c9l llev\u00f3 a cabo una cruzada y los resultados fueron de gran bendici\u00f3n. Tambi\u00e9n se form\u00f3 un grupo de espa\u00f1oles. Con el tiempo, la iglesia fue organizada con 30 miembros.\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403562\"><\/a><b><strong>Sittee River:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">El hermano Thomas Walker, un predicador laico ardiente y di\u00e1cono de la iglesia de Belice Southside tiene parientes que viven en la aldea de Sittee River. A menudo iba a visitarlos y darles el mensaje de salvaci\u00f3n. Viendo que ellos y otros estaban interesados en aprender m\u00e1s acerca de Jes\u00fas, el hermano Walker busc\u00f3 la ayuda del Pastor Woodbourne.<\/p><p style=\"font-weight: 400;\">Esto fue un trabajo muy dif\u00edcil, puesto que en esos d\u00edas los viajes eran hechos solo por barcos la cual algunos tem\u00edan este modo de transporte. La familia de Reynolds, que ya viv\u00eda all\u00ed se uni\u00f3 a ellos en una cruzada. Veintisiete personas entregaron sus corazones a Jes\u00fas. Entre los bautizados estaba el hermano David Reynolds, quien don\u00f3 el terreno donde se construy\u00f3 la primera iglesia.\u00a0\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403563\"><\/a><b><strong>Placencia:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Durante muchos a\u00f1os la hermana T. Cabral ha sido la &#8216;campeona&#8217; de la obra en Placencia hasta que ella fue capaz de formar un grupo para adorar y glorificar el nombre de Dios. Sirvi\u00f3 a la comunidad bien con su talento que Dios le hab\u00eda dado, atendiendo a los enfermos, y en especial a las mujeres embarazadas en el pueblo. Ella es respetada por todo el pueblo por el buen trabajo que ha hecho a trav\u00e9s de los a\u00f1os.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403564\"><\/a><b><strong>DISTRITO DE TOLEDO<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403565\"><\/a><b><strong>Monkey River:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">A finales de 1930 el evangelista Astleford de Canad\u00e1 lanz\u00f3 una cruzada en la aldea de Monkey River. Las personas que nunca hab\u00edan o\u00eddo el evangelio predicado de esta manera ten\u00edan hambre y sed por el evangelio y asist\u00edan cada noche a la cruzada.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">El Sr. Albert Coleman y su familia, asist\u00edan a estas reuniones, estuvieron ausentes durante dos semanas, lejos del lugar de la cruzada por motivos personales. Sin embargo, cuando regresaron, siempre ten\u00edan hambre y sed de la palabra de Dios que estaban aprendiendo por medio del evangelista.<\/p><p style=\"font-weight: 400;\">Al notificar al Pastor Astleford de su inter\u00e9s en el mensaje, el pastor estudi\u00f3 con ellos todas las lecciones que ellos no tuvieron la oportunidad de escuchar.<\/p><p style=\"font-weight: 400;\">Al final de la conferencia, \u00e9l y su familia y otras personas que asistieron a las reuniones, fueron bautizados. Y continuaron adorando en un edificio que la se\u00f1ora Carmen Wells hab\u00eda dado.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">En 1945 un hurac\u00e1n golpe\u00f3 el pueblo y una parte del edificio tuvo que ser reparado. mientras que algunos trabajaban en el edificio, algunos fueron a la granja y trajeron lo que ten\u00edan; y otros se fueron a pescar. Este alimento fue compartido entre los miembros que trabajaban y as\u00ed tengan lo suficiente para comer, mientras que el edificio estaba siendo reparado. Qu\u00e9 maravilloso era este esp\u00edritu de cooperaci\u00f3n.<\/p><p style=\"font-weight: 400;\">Algunos de los primeros miembros de este pueblo fueron: el hermano Albert y Christiline Coleman, Walter y Hazel Williams, Frank y Mildred Burgess, Clifford y Constance Artherly, Larry Artherly, Joseph Coe, Herman Wills, Daphne Wills, Rhoda Wills, y the Garbutt\u2019s.\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">La obra avanz\u00f3 un poco m\u00e1s con los siguientes pastores: Fulton Archbold, Bernard Woodbourne, y Caleb Clayton.<\/p><p style=\"font-weight: 400;\">Por muchos a\u00f1os la iglesia adventista era la \u00fanica en la aldea. A pesar que los pastores no pod\u00edan visitar a menudo, porque el transporte en esos d\u00edas era por mar, la cual muchos ten\u00edan miedo, pero esto no paro el progreso de la iglesia. Los l\u00edderes de la misi\u00f3n a menudo ordenaron a los miembros de iglesias para su constancia, mientras que los visitantes siempre aprecian esta iglesia por su esp\u00edritu de motivaci\u00f3n.<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403566\"><\/a><b><strong>Punta Gorda:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Se hicieron tres intentos de llevar el mensaje adventista a la ciudad m\u00e1s remota en el pa\u00eds de Belice, que era Punta Gorda. La primera fue por el Pastor C. Goodrich en 1900 que bautiz\u00f3 a tres personas. El segundo intento fue hecha por el evangelista RT Rankin, el entonces era presidente de la misi\u00f3n de Belice de la Iglesia Adventista del s\u00e9ptimo d\u00eda, acompa\u00f1ado por el hermano Albert Coleman y su familia de la iglesia Monkey River. Se llevaron a cabo reuniones de evangelizaci\u00f3n durante dos meses y cinco personas fueron bautizadas.\u00a0\u00a0En 1972, el tercer intento fue hecho por el hermano y la hermana Petronilo Romero. Como resultado de su esfuerzo, cinco personas fueron bautizadas.<\/p><p style=\"font-weight: 400;\">Pastor Coe llev\u00f3 a cabo una cruzada en Punta Gorda y con la ayuda de Dios se bautizaron 12 personas. El hermano Juan Weatherburne ten\u00eda una tienda en una de las calles del pueblo de Punta Gorda. Un voluntario llamado John Moore usualmente se deten\u00eda a comprar y una vez vio en la vitrina, un Curso B\u00edblico de la Voz de la Profec\u00eda. Esto le llam\u00f3 la atenci\u00f3n, y despu\u00e9s de una conversaci\u00f3n con el due\u00f1o de la tienda, fue inscrito en el curso. El Sr. Moore estudi\u00f3 y respondi\u00f3 a todas las preguntas en cada lecci\u00f3n, en corto tiempo hasta que lleg\u00f3 a la lecci\u00f3n 12, titulado &#8220;el mandamiento que casi todo el mundo est\u00e1 rompiendo&#8221;. , y dijo que le gustar\u00eda una explicaci\u00f3n sobre este tema, y el pastor Coe le dio la explicaci\u00f3n y el voluntario mencion\u00f3 que cre\u00eda que el Domingo era el d\u00eda de reposo, pero que a trav\u00e9s del curso de la Biblia, estaba aprendiendo de manera diferente.\u00a0\u00a0\u00a0<\/p><p style=\"font-weight: 400;\">El Sr. Moore estaba convencido con la respuesta de la Biblia a su pregunta y despu\u00e9s de nuevos estudios, junto con los dem\u00e1s fue bautizado, convirti\u00e9ndose as\u00ed en un miembro de la Iglesia Adventista del s\u00e9ptimo d\u00eda de Punta Gorda.\u00a0\u00a0El grupo de Punta Gorda se convirti\u00f3 en una iglesia organizada cuando el Hugh Blackman era presidente de la misi\u00f3n y el hermano Marlon Moody como tesorero.<a href=\"http:\/\/cwhite.unadeca.net\/index.php\/es\/article-category\/investigaciones\/historia-de-la-iglesia\/belice#_ftn1\" name=\"_ftnref1\"><\/a><\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403567\"><\/a><b><strong>CRECIMIENTO DE LA IGLESIA<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><table style=\"font-weight: 400;\" width=\"678\"><tbody><tr><td width=\"140\"><p>Nivel<\/p><\/td><td width=\"362\"><p>Administradores<\/p><\/td><td width=\"176\"><p>A\u00f1o<\/p><\/td><\/tr><tr><td width=\"140\"><p>Misi\u00f3n<\/p><\/td><td width=\"362\"><p>(La parte de abajo)<\/p><\/td><td width=\"176\"><p>No hay<\/p><\/td><\/tr><tr><td width=\"140\"><p>Conferencia<\/p><\/td><td width=\"362\"><p>Presidente: Pr. Ernal Scott. Secretario: Pr.\u00a0\u00a0Paul Casanova\u00a0<br \/>Tesorero: Mr. Abilio Cima.<\/p><\/td><td width=\"176\"><p>4 de Julio de 2004<\/p><\/td><\/tr><tr><td width=\"140\"><p>Uni\u00f3n<\/p><\/td><td width=\"362\"><p>Presidente: Pr. Denish\u00a0\u00a0Slusher\u00a0<br \/>\u00a0Secretario: Pr.\u00a0Luis Jesse\u00a0<br \/>\u00a0Tesorero:\u00a0\u00a0Mr. Abilo Cima<\/p><\/td><td width=\"176\"><p>June 1. 2008<\/p><\/td><\/tr><\/tbody><\/table><p style=\"font-weight: 400;\"><b><strong>\u00a0<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403568\"><\/a><b><strong>Belice como Misi\u00f3n:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Las oficinas de Belice estaban localizadas en Gabourel cerca de la iglesia St. Mary. Estos son los pastores quienes sirvieron como presidentes de la misi\u00f3n, Astleford de Canada, Fred I. Mohr, Fulton Archbold, John Williams, R.T. Rankin, Elden Ford, Frank Skoretz, Wintson Cunningham, James Kaine, L.V. Mcmillan, Gary Gregory, Hugh Blackman, Victor Sheperd y Dennis Slusher. Estos son los que sirvieron como secretarias, Edith White, Dorothy Carter, y Danalyn Sebastian. Estos son los nombres de los tesoreros, Ivy Usher, Dolores Mann, Mr. Oscar Oliver, Marlon Moody, Harold Premdas y Jose Smith.\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403569\"><\/a><b><strong>La iglesia en lo actual:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">A Dios sea la honra y gloria por la obra que sigue creciendo en el pa\u00eds de Belice, de acuerdo los libros de la Uni\u00f3n de la iglesia adventista de Belice hay 40.000 miembros, hasta el momento hay 17 pastores trabajando mano en mano llevando el mensaje a los todav\u00eda no han conocido del amor de Jes\u00fas. Le demos gracias a Dios que su iglesia es progresando, porque se est\u00e1n formando tres regiones la cual ser\u00e1n misiones con la voluntad de Dios.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403570\"><\/a><b><strong>CONCLUSI\u00d3N<\/strong><\/b><\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Dios siempre cumple con sus promesas. La iglesia adventista del s\u00e9ptimo d\u00eda de Belice prospero porque Dios es el capit\u00e1n de esta iglesia. Dios nos promete que \u00e9l va delante de nosotros y que siempre estar\u00e1 con nosotros y por lo tanto no hay nada que temer. Hab\u00eda hombres quienes fueron inspirados por el Esp\u00edritu Santo, llamado por Dios quienes realizaron la obra del evangelio sin temor. Hombre que su blanco era trabajara para Dios y depositaron su fe en Dios. Nunca se quejaron con la obra porque su primero amor era Dios. La iglesia de Dios nunca va a fracasar porque Dios nos guio desde el inicio y no seguir\u00e1 gui\u00e1ndonos hasta el futuro.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><a name=\"_Toc394403571\"><\/a><b><strong>BIBLIOGRAF\u00cdA<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><b><strong>\u00a0<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><b><strong>Libro:<\/strong><\/b><\/p><p style=\"font-weight: 400;\">Coe Ellis. The Journey of the Church Then and Now.\u00a0\u00a0Belize: Edited by Ann-marie\u00a0\u00a0\u00a0\u00a0\u00a0Williams, 2006.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\"><b><strong>Internet:<\/strong><\/b><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/es.belize.fm\/moneda-dlar-de-belice\/\">http:\/\/es.belize.fm\/moneda-dlar-de-belice\/<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/es.wikipedia.org\/wiki\/Belice\">http:\/\/es.wikipedia.org\/wiki\/Belice<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/es.wikipedia.org\/wiki\/Cultura_de_Belice\">http:\/\/es.wikipedia.org\/wiki\/Cultura_de_Belice<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/es.wikipedia.org\/wiki\/D%C3%B3lar_belice%C3%B1o\">http:\/\/es.wikipedia.org\/wiki\/D%C3%B3lar_belice%C3%B1o<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/es.wikipedia.org\/wiki\/Historia_de_Belice\">http:\/\/es.wikipedia.org\/wiki\/Historia_de_Belice<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/www.datosmacro.com\/demografia\/poblacion\/belice\">http:\/\/www.datosmacro.com\/demografia\/poblacion\/belice<\/a><\/p><p style=\"font-weight: 400;\"><a href=\"http:\/\/www.studylands.com\/es\/guia-paises\/BZ-culture.htm\">http:\/\/www.studylands.com\/es\/guia-paises\/BZ-culture.htm<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2d4eb97c sidebar\" data-id=\"2d4eb97c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a0ba073 elementor-widget elementor-widget-sidebar\" data-id=\"5a0ba073\" data-element_type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section id=\"search-2\" class=\"widget widget_search\"><form rol=\"search\" method=\"GET\" action=\"https:\/\/unadeca.net\/cwhite\/\">\n  <input type=\"search\"class=\"form-control\"\n  placeholder=\"Buscar\"\n  name=\"s\"\n  title=\"Buscar\"\n  value=\"\">\n<\/form>\n<\/section><section id=\"latest_news-2\" class=\"widget widget_latest_news\"><h2 class=\"widget-title\">Otras publicaciones<\/h2><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/08\/10\/pensamiento-del-dia-336\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">10-08-2026<\/h5>\n                <p>\u201cDios uni\u00f3 consigo nuestros corazones, mediante...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/08\/06\/pensamiento-del-dia-335\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">06-08-2026<\/h5>\n                <p>\u201cHermanos y hermanas, como colaboradores de Dios...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/08\/05\/pensamiento-del-dia-334\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">05-08-2026<\/h5>\n                <p>\u201cAhora este Salvador es nuestro intercesor que o...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/08\/04\/pensamiento-del-dia-333\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">04-08-2026<\/h5>\n                <p>4 de agosto&nbsp; \u201cAl contemplar a nuestro Inter...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/08\/03\/pensamiento-del-dia-332\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">03-08-2026<\/h5>\n                <p>\u201cCristo intercede por la raza perdida mediante s...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/07\/27\/pensamiento-del-dia-331\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">27-07-2026<\/h5>\n                <p>\u201cEl poder que cre\u00f3 todas las cosas es el poder ...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/07\/23\/pensamiento-del-dia-330\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">23-07-2026<\/h5>\n                <p>\u201cLos padres deben comprender que la educaci\u00f3n d...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/07\/16\/pensamiento-del-dia-329\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">16-07-2026<\/h5>\n                <p>\u201cPero lo que sobre todas las dem\u00e1s consideracio...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/07\/13\/pensamiento-del-dia-328\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">13-07-2026<\/h5>\n                <p>&#8220;El amor verdadero no es una pasi\u00f3n impetuo...<\/p>\n                <\/div>\n                <\/a><a href=\"https:\/\/unadeca.net\/cwhite\/2026\/07\/08\/pensamiento-del-dia-327\/\" class=\"sidebar-news\" >\n                <div class=\"media-body\" style=\"padding-bottom:20px !important;\">\n                    <h5 class=\"title-news\">PENSAMIENTO DEL D\u00cdA<\/h5>\n                <h5 class=\"date-news\">08-07-2026<\/h5>\n                <p>&#8220;Que Dios nos ayude para que podamos ser san...<\/p>\n                <\/div>\n                <\/a><\/ul><\/section><section id=\"latest_events-2\" class=\"widget widget_latest_events\"><h2 class=\"widget-title\">Pr\u00f3ximos Eventos<\/h2><p style=\"padding:25px;\">No listing found<\/p><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Historia de la iglesia: Belice INICIO DE LA OBRA ADVENTISTA EN BELICE &nbsp;&nbsp;&nbsp;&nbsp;Por: Ernesto Adler Clarke, Rigel Francis Clarke INTRODUCCI\u00d3N Es importante estudiar la historia de nuestra iglesia \u00bfPor qu\u00e9?&nbsp;&nbsp;La historia nos ayuda a entender el presente estudiando el pasado, la importancia de la historia reside en el hecho de que un pueblo que nos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2747","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/pages\/2747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/comments?post=2747"}],"version-history":[{"count":4,"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/pages\/2747\/revisions"}],"predecessor-version":[{"id":5799,"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/pages\/2747\/revisions\/5799"}],"wp:attachment":[{"href":"https:\/\/unadeca.net\/cwhite\/wp-json\/wp\/v2\/media?parent=2747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}